{"id":766,"date":"2025-08-20T10:16:00","date_gmt":"2025-08-20T08:16:00","guid":{"rendered":"https:\/\/lescorones.cat\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\/"},"modified":"2025-12-15T12:22:54","modified_gmt":"2025-12-15T11:22:54","slug":"premio-al-compromiso-con-la-sostenibilidad-en-les-corones","status":"publish","type":"post","link":"https:\/\/lescorones.cat\/es\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\/","title":{"rendered":"Premio al compromiso con la sostenibilidad en Les Corones"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Premio al compromiso con la sostenibilidad en Les Corones<\/h2>\n\n<p class=\"wp-block-paragraph\">El Restaurante Les Corones, especializado en pescado a la brasa, ha sido reconocido por su compromiso con la gesti\u00f3n ambiental. El premio se ha concedido entre restaurantes de las costas de Andaluc\u00eda, Catalu\u00f1a, Comunidad Valenciana, Islas Baleares, Regi\u00f3n de Murcia y Cantabria. Estamos comprometidos a ofrecer una experiencia culinaria \u00fanica para los amantes de la buena cocina y los buenos vinos. Y tambi\u00e9n con la sostenibilidad. Por eso en su momento apostamos por planes de calidad. \u00daltimamente, estamos adscritos a la Carta Europea de Turismo Sostenible. Una carta que va asociada al Parque Natural del Montgr\u00ed, las Islas Medas y el Baix Ter y al compromiso con las buenas pr\u00e1cticas ambientales.<\/p>\n\n<p class=\"wp-block-paragraph\">Los establecimientos premiados por su compromiso con la sostenibilidad y el medio ambiente han sido Surla (Tarifa, C\u00e1diz), El Farillo (Motril, Granada) y La Cova (Ayamonte, Huelva), en Andaluc\u00eda; Caterina (Gav\u00e0, Barcelona) y Les Corones (Torroella de Montgr\u00ed, Girona), en Catalu\u00f1a; Baobab Soul Kitchen &amp; Bar (Sant Joan Platja, Alicante) y Rub\u00e9n Miralles (Vinar\u00f2s, Castell\u00f3n), en la Comunidad Valenciana; Can Mimosa Eivissa (Santa Eul\u00e0ria des Riu, Ibiza), en las Islas Baleares; CP8 (Cabo de Palos, Cartagena, Murcia), en la Regi\u00f3n de Murcia; y La Torre by Mara\u00f1\u00f3n (Gal\u00ed, Cantabria), en Cantabria. En esta sexta edici\u00f3n del #MovimientoBanderasVerdes, Ecovidrio ha contado con la participaci\u00f3n de m\u00e1s de 15.000 hosteleros de 180 municipios de Andaluc\u00eda, Catalu\u00f1a, Comunidad Valenciana, Islas Baleares, la Regi\u00f3n de Murcia y, como novedad este a\u00f1o, Cantabria.<\/p>\n\n<h3 class=\"wp-block-heading\">Restaurante de referencia en la Gu\u00eda Michelin<\/h3>\n\n<p class=\"wp-block-paragraph\">En esta nueva edici\u00f3n, los hosteleros galardonados disfrutar\u00e1n de una exclusiva Master Class y una degustaci\u00f3n de varios platos a cargo del reconocido chef Ricard Camarena, que cuenta con dos estrellas Michelin. La historia de Les Corones est\u00e1 profundamente ligada al Pa\u00eds Vasco. Pere Miquel Carreras viaj\u00f3 a Guetaria para formarse en la t\u00e9cnica de cocinar el pescado a la brasa. All\u00ed aprendi\u00f3 de los maestros de los reconocidos restaurantes Elkano y Astillero. Tambi\u00e9n fue all\u00ed donde encarg\u00f3 una brasa hecha a medida que es la que hoy pod\u00e9is ver en Les Corones. Las besugueras tambi\u00e9n provienen del mismo lugar. Reconocido por la calidad gastron\u00f3mica, ya hace unos cuantos a\u00f1os que aparecemos como restaurante recomendado en la Gu\u00eda Michelin.<\/p>\n\n<p class=\"wp-block-paragraph\">Ecovidrio ha galardonado a los diez establecimientos hosteleros m\u00e1s responsables y comprometidos con la sostenibilidad de las costas espa\u00f1olas. Este premio forma parte del #MovimientoBanderasVerdes, la reconocida campa\u00f1a estival de <a href=\"https:\/\/www.ecovidrio.es\/hosteleros-sostenibles\" target=\"_blank\" rel=\"noreferrer noopener\">Ecovidrio<\/a> que reconoce el esfuerzo de la hosteler\u00eda local y el activismo de los municipios costeros por la circularidad durante el verano, especialmente en lo que respecta a la gesti\u00f3n correcta de los residuos.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Premio al compromiso con la sostenibilidad en Les Corones El Restaurante Les Corones, especializado en pescado a la brasa, ha sido reconocido por su compromiso con la gesti\u00f3n ambiental. El premio se ha concedido entre restaurantes de las costas de Andaluc\u00eda, Catalu\u00f1a, Comunidad Valenciana, Islas Baleares, Regi\u00f3n de Murcia y Cantabria. Estamos comprometidos a ofrecer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":767,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Premio al compromiso con la sostenibilidad en Les Corones - Restaurant braseria Les Corones<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lescorones.cat\/es\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Premio al compromiso con la sostenibilidad en Les Corones - Restaurant braseria Les Corones\" \/>\n<meta property=\"og:description\" content=\"Premio al compromiso con la sostenibilidad en Les Corones El Restaurante Les Corones, especializado en pescado a la brasa, ha sido reconocido por su compromiso con la gesti\u00f3n ambiental. El premio se ha concedido entre restaurantes de las costas de Andaluc\u00eda, Catalu\u00f1a, Comunidad Valenciana, Islas Baleares, Regi\u00f3n de Murcia y Cantabria. Estamos comprometidos a ofrecer [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lescorones.cat\/es\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurant braseria Les Corones\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RestaurantLesCorones\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-20T08:16:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:22:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lescorones.cat\/wp-content\/uploads\/2025\/12\/hosteleros-ganadores-webp-495x400-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"495\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lescorones.cat\\\/es\\\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lescorones.cat\\\/es\\\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lescorones.cat\\\/es\\\/#\\\/schema\\\/person\\\/c3c262a7aa853d34f36eff43fb0b61ca\"},\"headline\":\"Premio al compromiso con la sostenibilidad en Les Corones\",\"datePublished\":\"2025-08-20T08:16:00+00:00\",\"dateModified\":\"2025-12-15T11:22:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lescorones.cat\\\/es\\\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\\\/\"},\"wordCount\":484,\"publisher\":{\"@id\":\"https:\\\/\\\/lescorones.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lescorones.cat\\\/es\\\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lescorones.cat\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/hosteleros-ganadores-webp-495x400-1.webp\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lescorones.cat\\\/es\\\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\\\/\",\"url\":\"https:\\\/\\\/lescorones.cat\\\/es\\\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\\\/\",\"name\":\"Premio al compromiso con la sostenibilidad en Les Corones - Restaurant braseria Les Corones\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lescorones.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lescorones.cat\\\/es\\\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lescorones.cat\\\/es\\\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lescorones.cat\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/hosteleros-ganadores-webp-495x400-1.webp\",\"datePublished\":\"2025-08-20T08:16:00+00:00\",\"dateModified\":\"2025-12-15T11:22:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lescorones.cat\\\/es\\\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lescorones.cat\\\/es\\\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lescorones.cat\\\/es\\\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lescorones.cat\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/hosteleros-ganadores-webp-495x400-1.webp\",\"contentUrl\":\"https:\\\/\\\/lescorones.cat\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/hosteleros-ganadores-webp-495x400-1.webp\",\"width\":495,\"height\":400,\"caption\":\"Collage de hosteleros con un contenedor peque\u00f1o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lescorones.cat\\\/es\\\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/lescorones.cat\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Premio al compromiso con la sostenibilidad en Les Corones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lescorones.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/lescorones.cat\\\/es\\\/\",\"name\":\"Restaurant Les Corones\",\"description\":\"Restaurant Les Corones, especialitzat en peix a la brasa a l&#039;Estartit\",\"publisher\":{\"@id\":\"https:\\\/\\\/lescorones.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lescorones.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lescorones.cat\\\/es\\\/#organization\",\"name\":\"Restaurant Les Corones\",\"url\":\"https:\\\/\\\/lescorones.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lescorones.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lescorones.cat\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/VERSIO_HORITZONTAL_WEB_Apaisat.jpg\",\"contentUrl\":\"https:\\\/\\\/lescorones.cat\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/VERSIO_HORITZONTAL_WEB_Apaisat.jpg\",\"width\":1754,\"height\":500,\"caption\":\"Restaurant Les Corones\"},\"image\":{\"@id\":\"https:\\\/\\\/lescorones.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RestaurantLesCorones\\\/\",\"https:\\\/\\\/www.instagram.com\\\/lescorones\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lescorones.cat\\\/es\\\/#\\\/schema\\\/person\\\/c3c262a7aa853d34f36eff43fb0b61ca\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c1982c580199072ebcdd08985eb4893dff370093e33e729a1d39f691ec661860?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c1982c580199072ebcdd08985eb4893dff370093e33e729a1d39f691ec661860?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c1982c580199072ebcdd08985eb4893dff370093e33e729a1d39f691ec661860?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/lescorones.cat\"],\"url\":\"https:\\\/\\\/lescorones.cat\\\/es\\\/author\\\/foward_ydjz1321\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Premio al compromiso con la sostenibilidad en Les Corones - Restaurant braseria Les Corones","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lescorones.cat\/es\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\/","og_locale":"es_ES","og_type":"article","og_title":"Premio al compromiso con la sostenibilidad en Les Corones - Restaurant braseria Les Corones","og_description":"Premio al compromiso con la sostenibilidad en Les Corones El Restaurante Les Corones, especializado en pescado a la brasa, ha sido reconocido por su compromiso con la gesti\u00f3n ambiental. El premio se ha concedido entre restaurantes de las costas de Andaluc\u00eda, Catalu\u00f1a, Comunidad Valenciana, Islas Baleares, Regi\u00f3n de Murcia y Cantabria. Estamos comprometidos a ofrecer [&hellip;]","og_url":"https:\/\/lescorones.cat\/es\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\/","og_site_name":"Restaurant braseria Les Corones","article_publisher":"https:\/\/www.facebook.com\/RestaurantLesCorones\/","article_published_time":"2025-08-20T08:16:00+00:00","article_modified_time":"2025-12-15T11:22:54+00:00","og_image":[{"width":495,"height":400,"url":"https:\/\/lescorones.cat\/wp-content\/uploads\/2025\/12\/hosteleros-ganadores-webp-495x400-1.webp","type":"image\/webp"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lescorones.cat\/es\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\/#article","isPartOf":{"@id":"https:\/\/lescorones.cat\/es\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\/"},"author":{"name":"admin","@id":"https:\/\/lescorones.cat\/es\/#\/schema\/person\/c3c262a7aa853d34f36eff43fb0b61ca"},"headline":"Premio al compromiso con la sostenibilidad en Les Corones","datePublished":"2025-08-20T08:16:00+00:00","dateModified":"2025-12-15T11:22:54+00:00","mainEntityOfPage":{"@id":"https:\/\/lescorones.cat\/es\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\/"},"wordCount":484,"publisher":{"@id":"https:\/\/lescorones.cat\/es\/#organization"},"image":{"@id":"https:\/\/lescorones.cat\/es\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\/#primaryimage"},"thumbnailUrl":"https:\/\/lescorones.cat\/wp-content\/uploads\/2025\/12\/hosteleros-ganadores-webp-495x400-1.webp","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/lescorones.cat\/es\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\/","url":"https:\/\/lescorones.cat\/es\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\/","name":"Premio al compromiso con la sostenibilidad en Les Corones - Restaurant braseria Les Corones","isPartOf":{"@id":"https:\/\/lescorones.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lescorones.cat\/es\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\/#primaryimage"},"image":{"@id":"https:\/\/lescorones.cat\/es\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\/#primaryimage"},"thumbnailUrl":"https:\/\/lescorones.cat\/wp-content\/uploads\/2025\/12\/hosteleros-ganadores-webp-495x400-1.webp","datePublished":"2025-08-20T08:16:00+00:00","dateModified":"2025-12-15T11:22:54+00:00","breadcrumb":{"@id":"https:\/\/lescorones.cat\/es\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lescorones.cat\/es\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lescorones.cat\/es\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\/#primaryimage","url":"https:\/\/lescorones.cat\/wp-content\/uploads\/2025\/12\/hosteleros-ganadores-webp-495x400-1.webp","contentUrl":"https:\/\/lescorones.cat\/wp-content\/uploads\/2025\/12\/hosteleros-ganadores-webp-495x400-1.webp","width":495,"height":400,"caption":"Collage de hosteleros con un contenedor peque\u00f1o"},{"@type":"BreadcrumbList","@id":"https:\/\/lescorones.cat\/es\/premio-al-compromiso-con-la-sostenibilidad-en-les-corones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/lescorones.cat\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Premio al compromiso con la sostenibilidad en Les Corones"}]},{"@type":"WebSite","@id":"https:\/\/lescorones.cat\/es\/#website","url":"https:\/\/lescorones.cat\/es\/","name":"Restaurant Les Corones","description":"Restaurant Les Corones, especialitzat en peix a la brasa a l&#039;Estartit","publisher":{"@id":"https:\/\/lescorones.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lescorones.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lescorones.cat\/es\/#organization","name":"Restaurant Les Corones","url":"https:\/\/lescorones.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lescorones.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/lescorones.cat\/wp-content\/uploads\/2025\/12\/VERSIO_HORITZONTAL_WEB_Apaisat.jpg","contentUrl":"https:\/\/lescorones.cat\/wp-content\/uploads\/2025\/12\/VERSIO_HORITZONTAL_WEB_Apaisat.jpg","width":1754,"height":500,"caption":"Restaurant Les Corones"},"image":{"@id":"https:\/\/lescorones.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RestaurantLesCorones\/","https:\/\/www.instagram.com\/lescorones"]},{"@type":"Person","@id":"https:\/\/lescorones.cat\/es\/#\/schema\/person\/c3c262a7aa853d34f36eff43fb0b61ca","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c1982c580199072ebcdd08985eb4893dff370093e33e729a1d39f691ec661860?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c1982c580199072ebcdd08985eb4893dff370093e33e729a1d39f691ec661860?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c1982c580199072ebcdd08985eb4893dff370093e33e729a1d39f691ec661860?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/lescorones.cat"],"url":"https:\/\/lescorones.cat\/es\/author\/foward_ydjz1321\/"}]}},"_links":{"self":[{"href":"https:\/\/lescorones.cat\/es\/wp-json\/wp\/v2\/posts\/766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lescorones.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lescorones.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lescorones.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lescorones.cat\/es\/wp-json\/wp\/v2\/comments?post=766"}],"version-history":[{"count":1,"href":"https:\/\/lescorones.cat\/es\/wp-json\/wp\/v2\/posts\/766\/revisions"}],"predecessor-version":[{"id":768,"href":"https:\/\/lescorones.cat\/es\/wp-json\/wp\/v2\/posts\/766\/revisions\/768"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lescorones.cat\/es\/wp-json\/wp\/v2\/media\/767"}],"wp:attachment":[{"href":"https:\/\/lescorones.cat\/es\/wp-json\/wp\/v2\/media?parent=766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lescorones.cat\/es\/wp-json\/wp\/v2\/categories?post=766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lescorones.cat\/es\/wp-json\/wp\/v2\/tags?post=766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}